{"id":1483,"date":"2022-10-31T17:12:10","date_gmt":"2022-10-31T16:12:10","guid":{"rendered":"http:\/\/ripagreen.com\/desherbage-des-ecoles\/"},"modified":"2023-11-06T15:02:09","modified_gmt":"2023-11-06T14:02:09","slug":"unkrautvernichtung-auf-schulgelanden","status":"publish","type":"page","link":"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/","title":{"rendered":"Unkrautvernichtung auf Schulgel\u00e4nden"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"page-applications.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1483","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Umweltfreundliche Unkrautvernichtung auf Ihren Schulen | Ripagreen<\/title>\n<meta name=\"description\" content=\"J\u00e4ten Sie Schulh\u00f6fe und Spielpl\u00e4tze sicher mit unserem thermischen Unkrautvernichter mit Hei\u00dfluftpulsation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Umweltfreundliche Unkrautvernichtung auf Ihren Schulen | Ripagreen\" \/>\n<meta property=\"og:description\" content=\"J\u00e4ten Sie Schulh\u00f6fe und Spielpl\u00e4tze sicher mit unserem thermischen Unkrautvernichter mit Hei\u00dfluftpulsation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/\" \/>\n<meta property=\"og:site_name\" content=\"Ripagreen\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T14:02:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ripagreen.com\/wp-content\/uploads\/2023\/06\/ripagreen-logo-large-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ripagreen.com\\\/de\\\/unkrautvernichtung-auf-schulgelanden\\\/\",\"url\":\"https:\\\/\\\/ripagreen.com\\\/de\\\/unkrautvernichtung-auf-schulgelanden\\\/\",\"name\":\"Umweltfreundliche Unkrautvernichtung auf Ihren Schulen | Ripagreen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ripagreen.com\\\/#website\"},\"datePublished\":\"2022-10-31T16:12:10+00:00\",\"dateModified\":\"2023-11-06T14:02:09+00:00\",\"description\":\"J\u00e4ten Sie Schulh\u00f6fe und Spielpl\u00e4tze sicher mit unserem thermischen Unkrautvernichter mit Hei\u00dfluftpulsation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ripagreen.com\\\/de\\\/unkrautvernichtung-auf-schulgelanden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ripagreen.com\\\/de\\\/unkrautvernichtung-auf-schulgelanden\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ripagreen.com\\\/de\\\/unkrautvernichtung-auf-schulgelanden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ripagreen.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unkrautvernichtung auf Schulgel\u00e4nden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ripagreen.com\\\/#website\",\"url\":\"https:\\\/\\\/ripagreen.com\\\/\",\"name\":\"Ripagreen\",\"description\":\"Le d\u00e9sherbage thermique \u00e0 air chaud puls\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/ripagreen.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ripagreen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ripagreen.com\\\/#organization\",\"name\":\"Ripagreen\",\"alternateName\":\"Sefmat\",\"url\":\"https:\\\/\\\/ripagreen.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ripagreen.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ripagreen.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/ripagreen-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/ripagreen.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/ripagreen-logo-1.png\",\"width\":696,\"height\":696,\"caption\":\"Ripagreen\"},\"image\":{\"@id\":\"https:\\\/\\\/ripagreen.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Umweltfreundliche Unkrautvernichtung auf Ihren Schulen | Ripagreen","description":"J\u00e4ten Sie Schulh\u00f6fe und Spielpl\u00e4tze sicher mit unserem thermischen Unkrautvernichter mit Hei\u00dfluftpulsation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/","og_locale":"de_DE","og_type":"article","og_title":"Umweltfreundliche Unkrautvernichtung auf Ihren Schulen | Ripagreen","og_description":"J\u00e4ten Sie Schulh\u00f6fe und Spielpl\u00e4tze sicher mit unserem thermischen Unkrautvernichter mit Hei\u00dfluftpulsation.","og_url":"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/","og_site_name":"Ripagreen","article_modified_time":"2023-11-06T14:02:09+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/ripagreen.com\/wp-content\/uploads\/2023\/06\/ripagreen-logo-large-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/","url":"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/","name":"Umweltfreundliche Unkrautvernichtung auf Ihren Schulen | Ripagreen","isPartOf":{"@id":"https:\/\/ripagreen.com\/#website"},"datePublished":"2022-10-31T16:12:10+00:00","dateModified":"2023-11-06T14:02:09+00:00","description":"J\u00e4ten Sie Schulh\u00f6fe und Spielpl\u00e4tze sicher mit unserem thermischen Unkrautvernichter mit Hei\u00dfluftpulsation.","breadcrumb":{"@id":"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ripagreen.com\/de\/unkrautvernichtung-auf-schulgelanden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ripagreen.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unkrautvernichtung auf Schulgel\u00e4nden"}]},{"@type":"WebSite","@id":"https:\/\/ripagreen.com\/#website","url":"https:\/\/ripagreen.com\/","name":"Ripagreen","description":"Le d\u00e9sherbage thermique \u00e0 air chaud puls\u00e9","publisher":{"@id":"https:\/\/ripagreen.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ripagreen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ripagreen.com\/#organization","name":"Ripagreen","alternateName":"Sefmat","url":"https:\/\/ripagreen.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ripagreen.com\/#\/schema\/logo\/image\/","url":"https:\/\/ripagreen.com\/wp-content\/uploads\/2023\/06\/ripagreen-logo-1.png","contentUrl":"https:\/\/ripagreen.com\/wp-content\/uploads\/2023\/06\/ripagreen-logo-1.png","width":696,"height":696,"caption":"Ripagreen"},"image":{"@id":"https:\/\/ripagreen.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ripagreen.com\/de\/wp-json\/wp\/v2\/pages\/1483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripagreen.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ripagreen.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ripagreen.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ripagreen.com\/de\/wp-json\/wp\/v2\/comments?post=1483"}],"version-history":[{"count":3,"href":"https:\/\/ripagreen.com\/de\/wp-json\/wp\/v2\/pages\/1483\/revisions"}],"predecessor-version":[{"id":2248,"href":"https:\/\/ripagreen.com\/de\/wp-json\/wp\/v2\/pages\/1483\/revisions\/2248"}],"wp:attachment":[{"href":"https:\/\/ripagreen.com\/de\/wp-json\/wp\/v2\/media?parent=1483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}